{"id":4370,"date":"2023-12-10T09:57:07","date_gmt":"2023-12-10T08:57:07","guid":{"rendered":"https:\/\/riserooted.nl\/?page_id=4370"},"modified":"2024-02-07T08:59:28","modified_gmt":"2024-02-07T07:59:28","slug":"algemene-voorwaarden","status":"publish","type":"page","link":"https:\/\/riserooted.nl\/de\/algemene-voorwaarden\/","title":{"rendered":"Gesch\u00e4ftsbedingungen"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"4370\" class=\"elementor elementor-4370\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7fd3cd3 e-flex e-con-boxed e-con e-parent\" data-id=\"7fd3cd3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-05572c0 elementor-widget elementor-widget-heading\" data-id=\"05572c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Allgemeine Gesch\u00e4ftsbedingungen Praxis Rise Rooted<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-529ff13 elementor-widget elementor-widget-text-editor\" data-id=\"529ff13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Miriam Terbon\u00dfen \u2013 Praxis Rise Rooted<\/p>\n<p>Moesstraat 20<\/p>\n<p>9717JT Groningen<\/p>\n<p>www.riserooted.nl<\/p>\n<p>info@riserooted.nl<\/p>\n<p>KvK-nummer: 76555569<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ccd5e92 elementor-widget elementor-widget-heading\" data-id=\"ccd5e92\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Artikel 1 | G\u00fcltigkeit der vorliegenden Bestimmungen und Bedingungen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8152fcd elementor-widget elementor-widget-text-editor\" data-id=\"8152fcd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>1.1 Diese Bedingungen gelten f\u00fcr alle mit der Praxis Rise Rooted abgeschlossenen Vertr\u00e4ge. Ein Vertrag bezieht sich auf die Erbringung einer Dienstleistung im Rahmen der komplement\u00e4ren Therapie.<\/p>\n<p>1.2 Diese Bedingungen gelten f\u00fcr alle Angebote der Praxis Rise Rooted, unabh\u00e4ngig davon, ob diese zu einem Vertrag gef\u00fchrt haben.<\/p>\n<p>1.3 In diesen Bedingungen wird Praxis Rise Rooted als Auftragnehmer bezeichnet, w\u00e4hrend die andere Partei, der Klient\/die Klientin, oder der Kunde\/die Kundin, als Auftraggeber bezeichnet wird. Ein Auftraggeber kann eine nat\u00fcrliche oder juristische Person sein.<\/p>\n<p>1.4 Allgemeine Gesch\u00e4ftsbedingungen oder Lieferbedingungen des Auftraggebers gelten nicht, es sei denn, dass sie vom Auftragnehmer schriftlich akzeptiert worden sind.<\/p>\n<p>1.5 Mit dem Auftrag zur Durchf\u00fchrung einer komplement\u00e4rmedizinischen Behandlung werden diese Allgemeinen Gesch\u00e4ftsbedingungen anerkannt. Von diesen Allgemeinen Gesch\u00e4ftsbedingungen abweichende Sonderregelungen sind nur verbindlich, wenn sie schriftlich vereinbart werden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-be4dcfa elementor-widget elementor-widget-heading\" data-id=\"be4dcfa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Artikel\t2\t|\tAngebote<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a33aaf2 elementor-widget elementor-widget-text-editor\" data-id=\"a33aaf2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>2.1 Alle Angebote und\/oder Kostenvoranschl\u00e4ge sind unverbindlich, sofern nicht ausdr\u00fccklich anders angegeben.<\/p><p>2.2 M\u00fcndliche Angebote von Praxis Rise Rooted sind nicht bindend, es sei denn, sie werden schriftlich best\u00e4tigt.<\/p><p>2.3 Soweit nicht anders vereinbart, h\u00e4lt sich Praxis Rise Rooted an ihre Angebote 14 Tage gebunden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ca7c568 elementor-widget elementor-widget-heading\" data-id=\"ca7c568\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Artikel 3 | Vereinbarung<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-94cc009 elementor-widget elementor-widget-text-editor\" data-id=\"94cc009\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>3.1 Der Vertrag \u00fcber die Erbringung von Zusatzleistungen wird erst durch eine schriftliche Best\u00e4tigung der Praxis Rise Rooted verbindlich. Diese schriftliche Best\u00e4tigung (Behandlungsvertrag) kann per E-Mail versandt oder per Post ausgedruckt werden.<\/p><p>3.2 Jeder mit Praxis Rise Rooted abgeschlossene Vertrag enth\u00e4lt die aufl\u00f6sende Bedingung, dass der Kunde eine ausreichende Kreditw\u00fcrdigkeit nachweist. Diese Beurteilung wird ausschlie\u00dflich von Praxis Rise Rooted vorgenommen. Der Kunde wird Praxis Rise Rooted erlauben, wenn n\u00f6tig, Informationen \u00fcber ihn anzufordern.<\/p><p>3.3 Daten und\/oder Informationen, die Praxis Rise Rooted dem Auftraggeber zur Verf\u00fcgung stellt, wie z.B. Arbeitsprogramme, Schulungen und Materialien f\u00fcr Meditation und dergleichen, sowie gedruckte Dokumente, Zeichnungen, Abbildungen und dergleichen von Praxis Rise Rooted, sind f\u00fcr Praxis Rise Rooted nicht bindend und werden in gutem Vertrauen gegeben. Der Auftraggeber hat daf\u00fcr Sorge zu tragen, dass die genannten Materialien weder kopiert noch Dritten zug\u00e4nglich gemacht werden, oder dass Dritte \u00fcber deren Inhalt informiert werden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7fe49c9 elementor-widget elementor-widget-heading\" data-id=\"7fe49c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Artikel 4 | Allgemeine Gesch\u00e4ftsbedingungen von Vertragspartnern und\/oder Dritten<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9aade05 elementor-widget elementor-widget-text-editor\" data-id=\"9aade05\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>4.1 Praxis Rise Rooted erkennt die Anwendbarkeit von Allgemeinen Gesch\u00e4ftsbedingungen von Vertragspartnern und\/oder Dritten nur an, wenn diese ausdr\u00fccklich schriftlich vereinbart werden.<\/p><p>4.2 Die Anwendbarkeit der vorgenannten Allgemeinen Gesch\u00e4ftsbedingungen ber\u00fchrt jedoch nicht die Anwendbarkeit der Allgemeinen Gesch\u00e4ftsbedingungen von Praxis Rise Rooted.<\/p><p>4.3 Allgemeine Gesch\u00e4ftsbedingungen werden von Praxis Rise Rooted nur unter den oben genannten Bedingungen akzeptiert und gelten nur f\u00fcr die beabsichtigte Transaktion. Sp\u00e4tere Transaktionen werden nicht automatisch wieder \u00fcber diese Kaufbedingungen abgewickelt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1aaf4a1 elementor-widget elementor-widget-heading\" data-id=\"1aaf4a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Artikel 5 | Geistige Eigentumsrechte<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f69d9c4 elementor-widget elementor-widget-text-editor\" data-id=\"f69d9c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>5.1 Praxis Rise Rooted beh\u00e4lt sich alle Rechte am geistigen Eigentum von Praxis Rise Rooted zur Verf\u00fcgung gestellten Designs, Bildern, Zeichnungen, Modellen und Texten vor. Reproduktion, Weitergabe und Vervielf\u00e4ltigung sind nur mit ausdr\u00fccklicher schriftlicher Zustimmung von Miriam Terbon\u00dfen gestattet.<\/p><p>5.2 Die im ersten Absatz genannten Entw\u00fcrfe, Abbildungen, Zeichnungen, Texte und Modelle bleiben unver\u00e4nderliches Eigentum von Praxis Rise Rooted und m\u00fcssen auf erstes Versuchen hin unverz\u00fcglich zur\u00fcckgegeben werden. F\u00fcr jede Handlung, die gegen diese Bestimmung verst\u00f6\u00dft, hat die Gegenpartei eine Strafe von 5.000,00 \u20ac zu zahlen, unbeschadet des Rechts von Praxis Rise Rooted, vollen Schadenersatz zu fordern.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fdbab59 elementor-widget elementor-widget-heading\" data-id=\"fdbab59\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Artikel\t6\t|\tVerpflichtungen der Praxis Rise Rooted<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8e48824 elementor-widget elementor-widget-text-editor\" data-id=\"8e48824\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>6.1 Praxis Rise Rooted ist verpflichtet, die complementaire Begleitung gem\u00e4\u00df den Bestimmungen des Vertrages zu erf\u00fcllen. Diese Bestimmungen sind in der Behandlungsvereinbarung schriftlich festgehalten.<\/p><p>6.2 Praxis Rise Rooted f\u00fchrt die Behandlungen nach bestem Wissen und Gewissen und in \u00dcbereinstimmung mit den professionellen Anforderungen und Richtlinien der Berufsgruppen\/Berufsverb\u00e4nde und des Gesetzgebers durch.<\/p><p>6.3 Praxis Rise Rooted behandelt alle Kundendaten in \u00dcbereinstimmung mit den Richtlinien des AVG, der Allgemeinen Datenschutzverordnung.<\/p><p>6.4 Praxis Rise Rooted unterstellt alle Informationen und den Inhalt der gef\u00fchrten Gespr\u00e4che der Schweigepflicht. Informationen gelten als vertraulich, wenn dies vom Kunden mitgeteilt wurde oder sich aus der Art der Information ergibt. Die Vertraulichkeit entf\u00e4llt, wenn Praxis Rise Rooted aufgrund einer gesetzlichen Bestimmung oder eines Gerichtsbeschlusses verpflichtet ist, diese vertraulichen Informationen dem Gesetzgeber oder seinem Bevollm\u00e4chtigten offenzulegen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3920f06 elementor-widget elementor-widget-heading\" data-id=\"3920f06\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Artikel 7 | Verpflichtungen des Auftraggebers<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12da54b elementor-widget elementor-widget-text-editor\" data-id=\"12da54b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>7.1 Der Auftraggeber sorgt daf\u00fcr, dass Praxis Rise Rooted rechtzeitig Zugang hat zu: a. den f\u00fcr die Planung der Arbeiten erforderlichen (medizinischen) Daten und, falls erforderlich, der medizinischen Genehmigung einer im BIG-Register eingetragenen befugten Person. Sollte eine Konsultation mit Praxis Rise Rooted notwendig oder erw\u00fcnscht sein, kann mit Zustimmung des Auftraggebers eine Konsultation mit dem im BIG-Register eingetragenen Sachverst\u00e4ndigen stattfinden. b. \u00dcber den Raum, in dem die Arbeiten durchgef\u00fchrt werden sollen, wenn vereinbart wurde, dass die Behandlungen am Standort des Auftraggebers durchgef\u00fchrt werden sollen. c. \u00dcber ausreichende M\u00f6glichkeiten zur Versorgung mit Produkten und anderen Notwendigkeiten. d. \u00dcber Anschlussm\u00f6glichkeiten f\u00fcr elektrische Ger\u00e4te, Beleuchtung, Heizung, Wasser und andere Energie, die f\u00fcr die Ausf\u00fchrung der Arbeiten ben\u00f6tigt wird, muss innerhalb von 25 Metern vorhanden sein. e. \u00dcber die M\u00f6glichkeit, ein gesichertes Wifi-Netz nutzen zu d\u00fcrfen.<\/p><p>7.2 Praxis Rise Rooted setzt als Bedingung f\u00fcr die Behandlung voraus, dass der Auftraggeber alle seine medizinischen Beschwerden, Probleme und Fragen dem (Haus-)Arzt und\/oder Facharzt vortr\u00e4gt und auch die Diagnose des Arztes und die damit verbundenen medizinischen Ratschl\u00e4ge befolgt. Auch wenn dies bedeutet, dass der Arzt r\u00e4t, die Behandlungen bei Practice Rise Rooted abzubrechen. Praxis Rise Rooted respektiert und handelt immer in \u00dcbereinstimmung mit den medizinischen Verordnungen von (Allgemein-)\u00c4rzten. Praxis Rise Rooted stellt keine medizinischen Diagnosen.<\/p><p>7.3 Der Auftraggeber ist verpflichtet, Wasser, Gas und Strom zur Verf\u00fcgung zu stellen, wenn die Behandlungen in den R\u00e4umlichkeiten des Auftraggebers stattfinden, ohne daf\u00fcr eine Entsch\u00e4digung zu verlangen.<\/p><p>7.4 Hat sich der Auftraggeber die Lieferung bestimmter Materialien und\/oder die Ausf\u00fchrung bestimmter Teile des Vertrages vorbehalten, so haftet er f\u00fcr die nicht rechtzeitige Lieferung oder Ausf\u00fchrung.<\/p><p>7.5 Wird der Beginn oder der Fortgang der Arbeiten durch Faktoren verz\u00f6gert, die der Auftraggeber zu vertreten hat, so k\u00f6nnen die daraus resultierenden Sch\u00e4den und Kosten f\u00fcr Praxis Rise Rooted dem Auftraggeber in Rechnung gestellt werden.<\/p><p>7.6 Kann der Auftraggeber einen Termin nicht wahrnehmen, muss er ihn so schnell wie m\u00f6glich, sp\u00e4testens jedoch 24 Stunden vor dem Termin, telefonisch oder per E-Mail bei Miriam Terbon\u00dfen absagen. Unterl\u00e4sst der Kunde dies, so wird Praxis Rise Rooted den gesamten Betrag f\u00fcr die vereinbarte Behandlung in Rechnung stellen.<\/p><p>7.7 Der Auftraggeber wird Praxis Rise Rooted alle Daten zur Verf\u00fcgung stellen, die der Gesetzgeber als notwendig erachtet hat.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c609e6 elementor-widget elementor-widget-heading\" data-id=\"9c609e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Artikel 8 | Beauftragung von Arbeiten an dritte Parteien<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-97de252 elementor-widget elementor-widget-text-editor\" data-id=\"97de252\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Der Auftraggeber erteilt Praxis Rise Rooted die Erlaubnis, f\u00fcr die Ausf\u00fchrung des Auftrags die Hilfe und das Fachwissen Dritter in Anspruch zu nehmen. Praxis Rise Rooted pr\u00fcft von Fall zu Fall, ob dies notwendig ist, und erkl\u00e4rt dem Auftraggeber diese Entscheidung immer, bevor der Schritt zur Hinzuziehung des externen Experten unternommen wird. Wenn der Kunde dies nicht w\u00fcnscht, wird dies respektiert und der gew\u00fcnschte Experte wird nicht hinzugezogen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f62c0b elementor-widget elementor-widget-heading\" data-id=\"6f62c0b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Artikel\t9\t|\tPreise<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e37113f e-flex e-con-boxed e-con e-parent\" data-id=\"e37113f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-89ef4da elementor-widget elementor-widget-text-editor\" data-id=\"89ef4da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\" translation-block\">9.1 Indien na het tijdstip van acceptatie van de opdracht door de overheid of vakorganisaties wijzigingen worden <br>aangebracht in de lonen, arbeidsvoorwaarden, of sociale bepalingen, heeft elk van de partijen het recht algehele <br>verrekening te verlangen<\/p><p>9.2 Unvorhergesehene zwischenzeitliche \u00c4nderungen der Materialpreise k\u00f6nnen in Rechnung gebracht werden.<\/p><p class=\" translation-block\">9.3 Indien de prijsfluctuatie meer dan 5% bedraagt van de overeengekomen transactie, hebben beide partijen het recht <br>algehele verrekening te verlangen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-098b121 elementor-widget elementor-widget-heading\" data-id=\"098b121\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Artikel 10 | Zus\u00e4tzliche und verringerte Arbeit<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d9d2b4 elementor-widget elementor-widget-text-editor\" data-id=\"3d9d2b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>10.1 Die Arbeiten umfassen nur das, was zwischen den Parteien schriftlich vereinbart worden ist.<\/p><p>10.2 Bei  complementairen Behandlungen sind zus\u00e4tzliche Arbeiten, die der Auftraggeber m\u00fcndlich oder schriftlich angefragt hat, abrechnungsf\u00e4hig. Es handelt sich um Arbeiten, die nicht im (Behandlungs-)Vertrag enthalten waren.<\/p><p>10.3 Kosten, die f\u00fcr Praxis Rise Rooted entstehen und deren Ursache nicht in ihrem Verschulden liegt, k\u00f6nnen dem Auftraggeber in Rechnung gestellt werden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-165acd9 elementor-widget elementor-widget-heading\" data-id=\"165acd9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Artikel 11 | Annullierung<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d613a9 elementor-widget elementor-widget-text-editor\" data-id=\"1d613a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>11.1 Wenn der Auftraggeber den Auftrag storniert und\/oder die Abnahme der Produkte verweigert, ist er verpflichtet, die bereits gekauften Materialien und\/oder die von Praktijk Rise Rooted im Zusammenhang mit der Vorbereitung des Auftrags geleisteten Arbeitsstunden zu akzeptieren und zu bezahlen, und zwar unabh\u00e4ngig davon, ob sie zum Selbstkostenpreis bearbeitet wurden oder nicht, einschlie\u00dflich der L\u00f6hne und Sozialabgaben, und ist im \u00dcbrigen verpflichtet, Praxis Rise Rooted eine vollst\u00e4ndige Verg\u00fctung f\u00fcr das bereits Geleistete zu zahlen.<\/p><p>11.2 Der Auftraggeber schuldet Praxis Rise Rooted au\u00dferdem als Schadenersatz einen Betrag von 1\/3 des vereinbarten Preises. Der Auftraggeber ist ferner verpflichtet, Praxis Rise Rooted von Anspr\u00fcchen Dritter freizustellen, die sich aus der Annullierung des Auftrags und\/oder der Ablehnung der Produkte ergeben.<\/p><p>11.3 Ungeachtet des vorigen Absatzes dieses Artikels beh\u00e4lt sich Praxis Rise Rooted alle Rechte vor, die vollst\u00e4ndige Erf\u00fcllung des Vertrages und\/oder einen vollst\u00e4ndigen Schadensersatz zu fordern.<\/p><p>11.4 Die Gew\u00e4hrung oder Nichtgew\u00e4hrung von Subventionen, Geb\u00fchren oder anderen Formen der Entsch\u00e4digung oder Finanzierung ist niemals ein Grund f\u00fcr die Annullierung erteilter Auftr\u00e4ge, es sei denn, es wurde schriftlich etwas anderes zwischen dem Auftraggeber und Praxis Rise Rooted vereinbart.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e53a1d1 elementor-widget elementor-widget-heading\" data-id=\"e53a1d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Artikel\t12\t|\tReklamation<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4198193 elementor-widget elementor-widget-text-editor\" data-id=\"4198193\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>12.1 Wenn der Aufragsgeber Praxis Rise Rooted nicht innerhalb von 8 Tagen ab dem Tag der Behandlung auf M\u00e4ngel hinweist, die bei einer gr\u00fcndlichen Untersuchung h\u00e4tten festgestellt werden k\u00f6nnen, wird davon ausgegangen, dass der Auftragsgeber mit dem Zustand, in dem die Dienstleistung erbracht wurde, einverstanden ist, und erlischt jegliches Recht auf Reklamation.\u00a0<\/p><p>12.2 Praxis Rise Rooted sollte die M\u00f6glichkeit haben, eingereichte Beschwerden zu pr\u00fcfen. Im Falle einer Einigung wird eine schriftliche Erkl\u00e4rung erstellt, die von beiden Parteien zu unterzeichnen ist.\u00a0<\/p><p>12.3 Wenn die Beanstandung nach Ansicht von Praxis Rise Rooted zutreffend ist, wird Praxis Rise Rooted entweder eine angemessene Entsch\u00e4digung bis maximal zum Rechnungswert der gelieferten Waren und Dienstleistungen zahlen oder daf\u00fcr sorgen, dass die aufgetretenen M\u00e4ngel behoben werden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c0defe elementor-widget elementor-widget-heading\" data-id=\"7c0defe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Artikel 13 | Haftung<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3bb13e5 elementor-widget elementor-widget-text-editor\" data-id=\"3bb13e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>13.1 Praxis Rise Rooted haftet nicht f\u00fcr Kosten, Sch\u00e4den und Zinsen, die als direkte oder indirekte Folge von: a. au\u00dfergew\u00f6hnlichen Umst\u00e4nden, wie in den folgenden Bedingungen n\u00e4her beschrieben; b. Handlungen oder Unterlassungen des Kunden anderer von ihm oder in seinem Namen besch\u00e4ftigter Personen; c. Sch\u00e4den an den gelieferten Waren infolge \u00e4u\u00dferer mechanischer, chemischer oder biologischer Einfl\u00fcsse; d. jeder anderen \u00e4u\u00dferen Ursache<\/p><p>13.2 Praxis Rise Rooted haftet bis zur H\u00f6he der Deckungssumme ihrer Versicherung f\u00fcr die im Behandlungsvertrag vereinbarten Leistungen - oder bis zum Rechnungswert f\u00fcr Sch\u00e4den an Ger\u00e4ten und Sachen. Die gesetzliche Haftung gilt nur insoweit, als sie durch das Verschulden von Praxis Rise Rooted oder derjenigen Personen entstanden ist, die von Praxis Rise Rooted bei der\/den der Praxis Rise Rooted \u00fcbertragenen Arbeit(en) besch\u00e4ftigt wurden.<\/p><p>13.3 Die vom Auftragnehmer erteilten Informationen und Ratschl\u00e4ge sind nur allgemeiner Natur und unverbindlich. Praxis Rise Rooted haftet nicht f\u00fcr Sch\u00e4den jeglicher Art, die aus einer Fehlinterpretation durch den Auftraggeber entstehen.<\/p><p>13.4 Praxis Rise Rooted haftet nicht f\u00fcr Sch\u00e4den jeglicher Art, die dadurch entstehen, dass Praxis Rise Rooted sich auf unrichtige und\/oder unvollst\u00e4ndige Angaben des Auftraggebers in Bezug auf relevante physische und\/oder psychische Zust\u00e4nde, die Einnahme von Medikamenten, die Arbeit oder bestimmte Formen von Freizeitaktivit\u00e4ten verlassen hat.<\/p><p>13.5 Die Teilnahme an einer Behandlung, einem Kurs oder einem Workshop erfolgt auf eigenes Risiko des Kunden.<\/p><p>13.6 Praxis Rise Rooted ist niemals haftbar f\u00fcr Folgesch\u00e4den.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bc6bcba elementor-widget elementor-widget-heading\" data-id=\"bc6bcba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Artikel\t14\t|\tAu\u00dfergew\u00f6hnliche Umst\u00e4nde<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ade409c elementor-widget elementor-widget-text-editor\" data-id=\"ade409c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>14. 1 Au\u00dfergew\u00f6hnliche Umst\u00e4nde, wie Sturmsch\u00e4den und andere Naturkatastrophen, Behinderung durch Dritte, Behinderung des Transports im Allgemeinen, Voll- oder Teilstreiks, Unruhen, Krieg oder Kriegsgefahr sowohl hier als auch im Herkunftsland der Materialien, Ausschl\u00fcsse, Verlust oder Besch\u00e4digung von Waren w\u00e4hrend des Transports zu Praxis Rise Rooted oder dem Kunden, Nichtlieferung oder versp\u00e4tete Lieferung von Waren durch Lieferanten von Praxis Rise Rooted Ex- und Importverbote, vollst\u00e4ndige oder teilweise Mobilisierung, behindernde Ma\u00dfnahmen einer Regierung, Feuer, Pannen und Unf\u00e4lle im Betrieb oder in den Transportmitteln von Praxis Rise Rooted oder in den Transportmitteln Dritter, die Auferlegung von Abgaben oder andere staatliche Ma\u00dfnahmen, die eine \u00c4nderung der tats\u00e4chlichen Umst\u00e4nde zur Folge haben, stellen f\u00fcr Praxis Rise Rooted Umst\u00e4nde dar, die sie von der Verpflichtung zur Lieferung von Produkten entbindet, bzw. die Ausf\u00fchrung der Behandlungen, ohne dass der Kunde ein Recht auf Schadenersatz jeglicher Art oder wie auch immer genannt geltend machen kann.<\/p><p>14.2 In diesen oder \u00e4hnlichen F\u00e4llen ist Praxis Rise Rooted berechtigt, den Vertrag nach eigenem Ermessen entweder zu k\u00fcndigen oder auszusetzen bzw. zu \u00e4ndern, bis die au\u00dfergew\u00f6hnlichen Umst\u00e4nde nicht mehr bestehen, wobei der Kunde verpflichtet ist, die erbrachten Leistungen zu bezahlen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9713111 elementor-widget elementor-widget-heading\" data-id=\"9713111\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Artikel 15 | Eigentumsvorbehalt<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b123317 elementor-widget elementor-widget-text-editor\" data-id=\"b123317\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>15.1 Solange Praxis Rise Rooted keine vollst\u00e4ndige Zahlung bez\u00fcglich einer Vereinbarung der Parteien \u00fcber die Durchf\u00fchrung von complementairer Behandlung oder den Verkauf von Produkten (einschlie\u00dflich eventueller Sch\u00e4den, Kosten und Zinsen) erhalten hat, bleiben die gelieferten Waren Eigentum von Praxis Rise Rooted.<\/p><p>15.2 Praxis Rise Rooted hat das Recht, diese Waren zur\u00fcckzufordern und in Besitz zu nehmen, wenn der  Kunde seinen Verpflichtungen nicht nachkommt, wenn er in Liquidation geht, einen Zahlungsaufschub beantragt oder erwirkt hat, f\u00fcr insolvent erkl\u00e4rt wird oder die Waren beschlagnahmt werden.<\/p><p>15.3 Alle Verf\u00fcgungshandlungen \u00fcber die verkaufte und gelieferte Ware sind dem Kunden untersagt, solange er seine Zahlungsverpflichtungen nicht erf\u00fcllt hat.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ba555d elementor-widget elementor-widget-heading\" data-id=\"5ba555d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Artikel 16 | Verzug und K\u00fcndigung<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef71f61 elementor-widget elementor-widget-text-editor\" data-id=\"ef71f61\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>16.1 Wenn der Auftraggeber in irgendeiner Weise gegen den Vertrag verst\u00f6\u00dft, befindet er sich bereits allein deswegen in Verzug, ohne dass eine Inverzugsetzung erforderlich ist. Unbeschadet der Bestimmungen des B\u00fcrgerlichen Gesetzbuchs hat Praxis Rise Rooted im Falle des Verzugs das Recht, den geschlossenen Vertrag auszusetzen und ihn nach eigenem Ermessen ohne gerichtliche Intervention ganz oder teilweise f\u00fcr aufgel\u00f6st zu erkl\u00e4ren.<\/p><p>16.2 Praxis Rise Rooted hat auch die im vorigen Absatz dieses Artikels genannten Rechte, wenn der Auftraggeber f\u00fcr insolvent erkl\u00e4rt wird oder Konkurs angemeldet wird, wenn er einen Zahlungsaufschub beantragt oder erwirkt hat, wenn sein Verm\u00f6gen beschlagnahmt wird, wenn sein Unternehmen liquidiert oder von einem oder mehreren Dritten \u00fcbernommen wird, oder wenn er beabsichtigt, die Niederlande zu verlassen. In all diesen F\u00e4llen werden alle Forderungen, die Praxis Rise Rooted gegen\u00fcber dem Auftraggeber hat, sofort f\u00e4llig und zahlbar.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a854ceb elementor-widget elementor-widget-heading\" data-id=\"a854ceb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Artikel 17 | Zahlung<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-20d14c0 elementor-widget elementor-widget-text-editor\" data-id=\"20d14c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>17.1 Soweit nicht ausdr\u00fccklich anders vereinbart, gelten die Zahlungsbedingungen: Waren und Dienstleistungen werden in Rechnung gestellt und sind sp\u00e4testens 14 Tage nach Erhalt auf das in der Rechnung angegebene Konto zu zahlen.<\/p>\n<p>17.2 Jede vom Auftragsgeber geleistete Zahlung dient in erster Linie zur Begleichung der von ihm geschuldeten Zinsen sowie der au\u00dfergerichtlichen und gerichtlichen Kosten, wie nachstehend beschrieben, und wird anschlie\u00dfend auf die \u00e4lteste offene Forderung angerechnet.<\/p>\n<p>17.3 Der Auftraggeber ger\u00e4t durch den blo\u00dfen Ablauf der vorgenannten Frist von vierzehn Tagen ab Rechnungsdatum in Verzug, ohne dass es einer Inverzugsetzung bedarf.<\/p>\n<p>17.4 Bei \u00dcberschreitung der vorgenannten Zahlungsfrist von vierzehn Tagen schuldet der Kunde Zinsen in H\u00f6he von 1 % pro Monat, wobei ein Teil eines Monats als ganzer Monat gez\u00e4hlt wird.<\/p>\n<p>17.5 Alle gerichtlichen und au\u00dfergerichtlichen Kosten, die dem Auftragnehmer im Zusammenhang mit einer Nichterf\u00fcllung\/Unterlassung durch den Auftraggeber entstehen, gehen zu Lasten des Auftraggebers.<\/p>\n<p>17.6 Bei Zahlungsverzug betragen die au\u00dfergerichtlichen Inkassokosten mindestens 10 % des einzutreibenden Betrags, mindestens jedoch 97,50 Euro.<\/p>\n<p>17.7 Der Auftragnehmer ist berechtigt, seine Arbeiten einzustellen, auch wenn eine feste Lieferfrist vereinbart wurde, wenn der Auftraggeber mit seinen Zahlungsverpflichtungen in Verzug ist.<\/p>\n<p>17.8 Der Auftragnehmer ist immer berechtigt, vor der Lieferung oder der Ausf\u00fchrung des Auftrags eine Sicherheit f\u00fcr die Erf\u00fcllung der Zahlungsverpflichtungen des Auftraggebers zu verlangen, die er f\u00fcr ausreichend h\u00e4lt. Die Weigerung des Auftraggebers, die geforderte Sicherheit zu leisten, gibt dem Auftragnehmer das Recht, den Vertrag durch eine entsprechende schriftliche Erkl\u00e4rung aufzul\u00f6sen, unbeschadet des Rechts des Auftragnehmers auf Ersatz der Kosten und des Gewinnausfalls.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d7ab2f8 elementor-widget elementor-widget-heading\" data-id=\"d7ab2f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Artikel 18 | Rechtsstreitigkeiten<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7aeefe6 elementor-widget elementor-widget-text-editor\" data-id=\"7aeefe6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>18.1 Alle Streitigkeiten, die sich aus den zwischen den Parteien geschlossenen Vertr\u00e4gen ergeben, einschlie\u00dflich der blo\u00dfen Eintreibung des geschuldeten Betrages, werden auf Wunsch von Praxis Rise Rooted vor dem Zivilgericht des Ortes ihrer Niederlassung verhandelt, soweit das Zivilgericht daf\u00fcr gesetzlich zust\u00e4ndig ist.<\/p><p>18.2 Die im vorigen Absatz erw\u00e4hnte Wahl des Gerichtsstandes ber\u00fchrt jedoch nicht das Recht von Praxis Rise Rooted, einen Streitfall dem Streitschlichtungsausschuss gem\u00e4\u00df dem Wkkgz-Gesetz vorzulegen.<\/p><p>18.3 Der 'Nationale Ombudsman' befasst sich mit Beschwerden \u00fcber die Jugendbetreuung, wenn es sich um eine Betreuung in einem so genannten Zwangsrahmen handelt, wie z.B. im Falle einer gerichtlich angeordneten Betreuung. Praxis Rise Rooted hat das Recht, eine Streitigkeit im Zusammenhang mit der geleisteten erg\u00e4nzenden Betreuung dem 'Nationalen Ombudsman' vorzulegen. Bei Beschwerden im Rahmen der freiwilligen Jugendbetreuung kann sich Praxis Rise Rooted an die AKJ-Vertrauenspersonen in der Jugendbetreuung wenden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Algemene Voorwaarden Praktijk Rise Rooted: Miriam Terbon\u00dfen &#8211; Praktijk Rise Rooted Moesstraat 20 9717JT Groningen www.riserooted.nl info@riserooted.nl KvK-nummer: 76555569 Artikel 1 | Geldigheid van deze voorwaarden 1.1 Deze voorwaarden zijn van toepassing op alle overeenkomsten die zijn aangegaan met Praktijk Rise Rooted. Een overeenkomst heeft betrekking op het verrichten van een dienst in het kader [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-4370","page","type-page","status-publish","hentry"],"blocksy_meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Praktijk Rise Rooted - Algemene Voorwaarden<\/title>\n<meta name=\"description\" content=\"Deze algemene voorwaarden zijn van toepassing op alle overeenkomsten die zijn aangegaan met Praktijk Rise Rooted.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/riserooted.nl\/de\/algemene-voorwaarden\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Praktijk Rise Rooted - Algemene Voorwaarden\" \/>\n<meta property=\"og:description\" content=\"Deze algemene voorwaarden zijn van toepassing op alle overeenkomsten die zijn aangegaan met Praktijk Rise Rooted.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/riserooted.nl\/de\/algemene-voorwaarden\/\" \/>\n<meta property=\"og:site_name\" content=\"Rise Rooted - Lichaamsgerichte Therapie Groningen\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61555201061704\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-07T07:59:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/riserooted.nl\/wp-content\/uploads\/2023\/10\/442a4638-fa48-4e5b-bafd-9e5393ec30db-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1705\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"15\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/riserooted.nl\\\/algemene-voorwaarden\\\/\",\"url\":\"https:\\\/\\\/riserooted.nl\\\/algemene-voorwaarden\\\/\",\"name\":\"Praktijk Rise Rooted - Algemene Voorwaarden\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/riserooted.nl\\\/#website\"},\"datePublished\":\"2023-12-10T08:57:07+00:00\",\"dateModified\":\"2024-02-07T07:59:28+00:00\",\"description\":\"Deze algemene voorwaarden zijn van toepassing op alle overeenkomsten die zijn aangegaan met Praktijk Rise Rooted.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/riserooted.nl\\\/algemene-voorwaarden\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/riserooted.nl\\\/algemene-voorwaarden\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/riserooted.nl\\\/algemene-voorwaarden\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/riserooted.nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Algemene Voorwaarden\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/riserooted.nl\\\/#website\",\"url\":\"https:\\\/\\\/riserooted.nl\\\/\",\"name\":\"Rise Rooted\",\"description\":\"Thuiskomen In Je Lichaam\",\"publisher\":{\"@id\":\"https:\\\/\\\/riserooted.nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/riserooted.nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/riserooted.nl\\\/#organization\",\"name\":\"Praktijk Rise Rooted\",\"url\":\"https:\\\/\\\/riserooted.nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/riserooted.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/riserooted.nl\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/logo-nl.png\",\"contentUrl\":\"https:\\\/\\\/riserooted.nl\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/logo-nl.png\",\"width\":1396,\"height\":1126,\"caption\":\"Praktijk Rise Rooted\"},\"image\":{\"@id\":\"https:\\\/\\\/riserooted.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=61555201061704\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/miriam-terbonssen-04b556217\\\/\",\"https:\\\/\\\/www.instagram.com\\\/riserooted.nl\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Praktijk Rise Rooted - Algemene Voorwaarden","description":"Deze algemene voorwaarden zijn van toepassing op alle overeenkomsten die zijn aangegaan met Praktijk Rise Rooted.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/riserooted.nl\/de\/algemene-voorwaarden\/","og_locale":"de_DE","og_type":"article","og_title":"Praktijk Rise Rooted - Algemene Voorwaarden","og_description":"Deze algemene voorwaarden zijn van toepassing op alle overeenkomsten die zijn aangegaan met Praktijk Rise Rooted.","og_url":"https:\/\/riserooted.nl\/de\/algemene-voorwaarden\/","og_site_name":"Rise Rooted - Lichaamsgerichte Therapie Groningen","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=61555201061704","article_modified_time":"2024-02-07T07:59:28+00:00","og_image":[{"width":2560,"height":1705,"url":"https:\/\/riserooted.nl\/wp-content\/uploads\/2023\/10\/442a4638-fa48-4e5b-bafd-9e5393ec30db-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"15\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/riserooted.nl\/algemene-voorwaarden\/","url":"https:\/\/riserooted.nl\/algemene-voorwaarden\/","name":"Praktijk Rise Rooted - Algemene Voorwaarden","isPartOf":{"@id":"https:\/\/riserooted.nl\/#website"},"datePublished":"2023-12-10T08:57:07+00:00","dateModified":"2024-02-07T07:59:28+00:00","description":"Deze algemene voorwaarden zijn van toepassing op alle overeenkomsten die zijn aangegaan met Praktijk Rise Rooted.","breadcrumb":{"@id":"https:\/\/riserooted.nl\/algemene-voorwaarden\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/riserooted.nl\/algemene-voorwaarden\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/riserooted.nl\/algemene-voorwaarden\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/riserooted.nl\/"},{"@type":"ListItem","position":2,"name":"Algemene Voorwaarden"}]},{"@type":"WebSite","@id":"https:\/\/riserooted.nl\/#website","url":"https:\/\/riserooted.nl\/","name":"Rise Rooted","description":"Thuiskomen In Je Lichaam","publisher":{"@id":"https:\/\/riserooted.nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/riserooted.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/riserooted.nl\/#organization","name":"Praktijk Rise Rooted","url":"https:\/\/riserooted.nl\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/riserooted.nl\/#\/schema\/logo\/image\/","url":"https:\/\/riserooted.nl\/wp-content\/uploads\/2024\/01\/logo-nl.png","contentUrl":"https:\/\/riserooted.nl\/wp-content\/uploads\/2024\/01\/logo-nl.png","width":1396,"height":1126,"caption":"Praktijk Rise Rooted"},"image":{"@id":"https:\/\/riserooted.nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61555201061704","https:\/\/www.linkedin.com\/in\/miriam-terbonssen-04b556217\/","https:\/\/www.instagram.com\/riserooted.nl\/"]}]}},"_links":{"self":[{"href":"https:\/\/riserooted.nl\/de\/wp-json\/wp\/v2\/pages\/4370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/riserooted.nl\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/riserooted.nl\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/riserooted.nl\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/riserooted.nl\/de\/wp-json\/wp\/v2\/comments?post=4370"}],"version-history":[{"count":76,"href":"https:\/\/riserooted.nl\/de\/wp-json\/wp\/v2\/pages\/4370\/revisions"}],"predecessor-version":[{"id":4571,"href":"https:\/\/riserooted.nl\/de\/wp-json\/wp\/v2\/pages\/4370\/revisions\/4571"}],"wp:attachment":[{"href":"https:\/\/riserooted.nl\/de\/wp-json\/wp\/v2\/media?parent=4370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}